{"id":10000669,"date":"2023-10-23T12:29:39","date_gmt":"2023-10-23T11:29:39","guid":{"rendered":"https:\/\/rochdalepetanque.com\/?post_type=tribe_events&#038;p=450"},"modified":"2023-10-23T12:30:44","modified_gmt":"2023-10-23T11:30:44","slug":"open-session","status":"publish","type":"tribe_events","link":"https:\/\/rochdalepetanque.com\/index.php\/event\/open-session\/2026-04-07\/","title":{"rendered":"Tuesday Afternoon Open Session"},"content":{"rendered":"<p>Join in our Tuesday afternoon open session, everyone welcome.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Join in our Tuesday afternoon open session, everyone welcome.<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[3],"class_list":["post-10000669","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-rochdale-petanque-events","cat_rochdale-petanque-events","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/rochdalepetanque.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/10000669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rochdalepetanque.com\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/rochdalepetanque.com\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/rochdalepetanque.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/rochdalepetanque.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/10000669\/revisions"}],"wp:attachment":[{"href":"https:\/\/rochdalepetanque.com\/index.php\/wp-json\/wp\/v2\/media?parent=10000669"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rochdalepetanque.com\/index.php\/wp-json\/wp\/v2\/tags?post=10000669"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/rochdalepetanque.com\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=10000669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}